{"id":162,"count":1,"description":"","link":"https:\/\/clinicadentalolivercoll.com\/ca\/tag\/gingivitis-ca\/","name":"gingivitis","slug":"gingivitis-ca","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>gingivitis archivos - Cl\u00ednica dental Oliver Coll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/tag\/gingivitis-ca\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"gingivitis archivos - Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadentalolivercoll.com\/ca\/tag\/gingivitis-ca\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica dental Oliver Coll\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/tag\\\/gingivitis-ca\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/tag\\\/gingivitis-ca\\\/\",\"name\":\"gingivitis archivos - Cl\u00ednica dental Oliver Coll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/tag\\\/gingivitis-ca\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/tag\\\/gingivitis-ca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"gingivitis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"description\":\"Cl\u00ednica dental en Matar\u00f3\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"width\":300,\"height\":300,\"caption\":\"Cl\u00ednica dental Oliver Coll\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ClinicaOliverColl\",\"https:\\\/\\\/www.instagram.com\\\/clinicaolivercoll\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"gingivitis archivos - Cl\u00ednica dental Oliver Coll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadentalolivercoll.com\/ca\/tag\/gingivitis-ca\/","og_locale":"ca_ES","og_type":"article","og_title":"gingivitis archivos - Cl\u00ednica dental Oliver Coll","og_url":"https:\/\/clinicadentalolivercoll.com\/ca\/tag\/gingivitis-ca\/","og_site_name":"Cl\u00ednica dental Oliver Coll","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/tag\/gingivitis-ca\/","url":"https:\/\/clinicadentalolivercoll.com\/ca\/tag\/gingivitis-ca\/","name":"gingivitis archivos - Cl\u00ednica dental Oliver Coll","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/tag\/gingivitis-ca\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/tag\/gingivitis-ca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadentalolivercoll.com\/ca\/"},{"@type":"ListItem","position":2,"name":"gingivitis"}]},{"@type":"WebSite","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","name":"Cl\u00ednica dental Oliver Coll","description":"Cl\u00ednica dental en Matar\u00f3","publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadentalolivercoll.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization","name":"Cl\u00ednica dental Oliver Coll","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","width":300,"height":300,"caption":"Cl\u00ednica dental Oliver Coll"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClinicaOliverColl","https:\/\/www.instagram.com\/clinicaolivercoll\/"]}]}},"_links":{"self":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/tags\/162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts?tags=162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}