{"id":4388,"date":"2019-02-27T23:40:04","date_gmt":"2019-02-27T23:40:04","guid":{"rendered":"https:\/\/olivercoll.staging.dissenyweb.com\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/"},"modified":"2026-02-27T16:02:02","modified_gmt":"2026-02-27T16:02:02","slug":"8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental","status":"publish","type":"post","link":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/","title":{"rendered":"8 consells que has de seguir abans de posar-te un implant dental"},"content":{"rendered":"<p>Encara que m\u00e9s del 80% dels implants col\u00b7locats segueixen funcionant adequadament despr\u00e9s de 15 anys, des de la Cl\u00ednica Dental Bucalis insistim que el pacient hauria de seguir alguns consells abans de decidir col\u00b7locar un implant dental:<\/p>\n<h2><span style=\"color: #6881a6;\">8 Consells que has de seguir abans de posar-te un implant dental<\/span><\/h2>\n<p>&#8211; Triar una <strong>cl\u00ednica de confian\u00e7a i amb refer\u00e8ncies<\/strong>.<\/p>\n<p>&#8211; Con\u00e8ixer personalment a l&#8217;especialista que realitzar\u00e0 la intervenci\u00f3. Moltes vegades s\u00f3n els intermediaris els que expliquen aquests tractaments i no s&#8217;ajusta a la realitat.<\/p>\n<p>&#8211; Entaular una relaci\u00f3 estreta i de m\u00fatua confian\u00e7a amb el implant\u00f2leg.<\/p>\n<p>&#8211; El centre escollit ha d&#8217;informar de tots els tractaments possibles, amb o sense implants dentals, aix\u00ed com el nombre d&#8217;implants o el tipus de pr\u00f2tesi definitiva que es proposa, ja sigui removible o fixa.<\/p>\n<p>&#8211; El pacient ha d&#8217;estar informat del<strong> tipus d&#8217;implant que va portar<\/strong> i la marca comercial. Actualment hi ha moltes cases comercials i cadascuna d&#8217;elles t\u00e9 diferents gammes d&#8217;implants. \u00c9s important tenir aquesta informaci\u00f3: marca, tipus de connexi\u00f3 i plataforma de l&#8217;implant, de cara a possibles problemes futurs.<\/p>\n<p>&#8211; Un altre dels factors a tenir en compte \u00e9s el temps de tractament. Des que comen\u00e7a la fase de la cirurgia fins al moment de reposar les dents perdudes mitjan\u00e7ant la pr\u00f2tesi definitiva. Agrupar els tractaments escur\u00e7a l&#8217;estada del pacient al centre i redueix el seu estr\u00e8s.<\/p>\n<p>&#8211; Tamb\u00e9 \u00e9s important determinar quin tipus de pr\u00f2tesi provisional portar\u00e0 el pacient fins que pugui realitzar-se el seu tractament definitiu, si removible o fixa, recolzada sobre dents o sobre implants.<\/p>\n<p>&#8211; Un altre dels aspectes importants \u00e9s que el pacient ha d&#8217;estar informat sobre qualsevol contratemps que pugui sorgir derivat de la col\u00b7locaci\u00f3 dels implants.<\/p>\n<p><img decoding=\"async\" class=\"lazyload aligncenter size-full wp-image-3652\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271000%27%20height%3D%27405%27%20viewBox%3D%270%200%201000%20405%27%3E%3Crect%20width%3D%271000%27%20height%3D%27405%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/franquicias-dentales2.jpg\" alt=\"\" width=\"1000\" height=\"405\"><\/p>\n<p>A la <a href=\"https:\/\/clinicadentalolivercoll.com\/ca\/\">Cl\u00ednica Dental Bucalis a Matar\u00f3<\/a> utilitzem sistemes d&#8217;implantologia m\u00e9s avan\u00e7ats i Implants Dentals m\u00e0xima qualitat, assegurant \u00e8xit i durabilitat a llarg termini, aix\u00ed com un proc\u00e9s sense dolor amb t\u00e8cniques molt avan\u00e7ades que no es troben en qualsevol cl\u00ednica dental.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encara que m\u00e9s del 80% dels implants col\u00b7locats segueixen funcionant  [&#8230;]<\/p>\n","protected":false},"author":8,"featured_media":4369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[56,74],"tags":[],"class_list":["post-4388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sense-categoria","category-tractaments-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8 consells que has de seguir abans de posar-te un implant dental - Cl\u00ednica dental Oliver Coll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8 consells que has de seguir abans de posar-te un implant dental - Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"og:description\" content=\"Encara que m\u00e9s del 80% dels implants col\u00b7locats segueixen funcionant [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClinicaOliverColl\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-27T23:40:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T16:02:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/slider-main2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"862\" \/>\n\t<meta property=\"og:image:height\" content=\"312\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pilar Oliver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pilar Oliver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/\"},\"author\":{\"name\":\"Pilar Oliver\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\"},\"headline\":\"8 consells que has de seguir abans de posar-te un implant dental\",\"datePublished\":\"2019-02-27T23:40:04+00:00\",\"dateModified\":\"2026-02-27T16:02:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/\"},\"wordCount\":373,\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/slider-main2.jpg\",\"articleSection\":{\"1\":\"Tractaments\"},\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/\",\"name\":\"8 consells que has de seguir abans de posar-te un implant dental - Cl\u00ednica dental Oliver Coll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/slider-main2.jpg\",\"datePublished\":\"2019-02-27T23:40:04+00:00\",\"dateModified\":\"2026-02-27T16:02:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/slider-main2.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/slider-main2.jpg\",\"width\":862,\"height\":312,\"caption\":\"Consejos antes del implante dental\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8 consells que has de seguir abans de posar-te un implant dental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"description\":\"Cl\u00ednica dental en Matar\u00f3\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"width\":300,\"height\":300,\"caption\":\"Cl\u00ednica dental Oliver Coll\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ClinicaOliverColl\",\"https:\\\/\\\/www.instagram.com\\\/clinicaolivercoll\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\",\"name\":\"Pilar Oliver\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"caption\":\"Pilar Oliver\"},\"description\":\"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/author\\\/pilar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8 consells que has de seguir abans de posar-te un implant dental - Cl\u00ednica dental Oliver Coll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/","og_locale":"ca_ES","og_type":"article","og_title":"8 consells que has de seguir abans de posar-te un implant dental - Cl\u00ednica dental Oliver Coll","og_description":"Encara que m\u00e9s del 80% dels implants col\u00b7locats segueixen funcionant [...]","og_url":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/","og_site_name":"Cl\u00ednica dental Oliver Coll","article_publisher":"https:\/\/www.facebook.com\/ClinicaOliverColl","article_published_time":"2019-02-27T23:40:04+00:00","article_modified_time":"2026-02-27T16:02:02+00:00","og_image":[{"width":862,"height":312,"url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/slider-main2.jpg","type":"image\/jpeg"}],"author":"Pilar Oliver","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Pilar Oliver","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/#article","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/"},"author":{"name":"Pilar Oliver","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a"},"headline":"8 consells que has de seguir abans de posar-te un implant dental","datePublished":"2019-02-27T23:40:04+00:00","dateModified":"2026-02-27T16:02:02+00:00","mainEntityOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/"},"wordCount":373,"publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/slider-main2.jpg","articleSection":{"1":"Tractaments"},"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/","url":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/","name":"8 consells que has de seguir abans de posar-te un implant dental - Cl\u00ednica dental Oliver Coll","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/#primaryimage"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/slider-main2.jpg","datePublished":"2019-02-27T23:40:04+00:00","dateModified":"2026-02-27T16:02:02+00:00","breadcrumb":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/#primaryimage","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/slider-main2.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/slider-main2.jpg","width":862,"height":312,"caption":"Consejos antes del implante dental"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/8-consells-que-has-de-seguir-abans-de-posar-te-un-implant-dental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadentalolivercoll.com\/ca\/"},{"@type":"ListItem","position":2,"name":"8 consells que has de seguir abans de posar-te un implant dental"}]},{"@type":"WebSite","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","name":"Cl\u00ednica dental Oliver Coll","description":"Cl\u00ednica dental en Matar\u00f3","publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadentalolivercoll.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization","name":"Cl\u00ednica dental Oliver Coll","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","width":300,"height":300,"caption":"Cl\u00ednica dental Oliver Coll"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClinicaOliverColl","https:\/\/www.instagram.com\/clinicaolivercoll\/"]},{"@type":"Person","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a","name":"Pilar Oliver","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","caption":"Pilar Oliver"},"description":"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente","url":"https:\/\/clinicadentalolivercoll.com\/ca\/author\/pilar\/"}]}},"_links":{"self":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/comments?post=4388"}],"version-history":[{"count":0,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/media\/4369"}],"wp:attachment":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/media?parent=4388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/categories?post=4388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/tags?post=4388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}