{"id":4223,"date":"2018-01-30T11:55:46","date_gmt":"2018-01-30T11:55:46","guid":{"rendered":"https:\/\/olivercoll.staging.dissenyweb.com\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/"},"modified":"2026-02-27T16:02:04","modified_gmt":"2026-02-27T16:02:04","slug":"que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges","status":"publish","type":"post","link":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/","title":{"rendered":"Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges?"},"content":{"rendered":"<p>A la Cl\u00ednica Dental Bucalis any a any observem que la preocupaci\u00f3 per l&#8217;aspecte f\u00edsic dels pacients s&#8217;incrementa. Fins fa uns anys les consultes es rebien sobre malalties o problemes bucodentals, per\u00f2 a poc a poc s\u00f3n m\u00e9s persones les que s&#8217;acosten preguntant per tractaments d&#8217;est\u00e8tica dental que millori el seu aspecte f\u00edsic i ajudi a incrementar la seva confian\u00e7a personal.<!--more--><br \/>\nAix\u00f2 tamb\u00e9 ve generat pels aven\u00e7os en el camp de l&#8217;odontologia que ens permet oferir uns tractaments m\u00e9s avan\u00e7ats i adaptats a les necessitats de la societat actual.<\/p>\n<p>A la Cl\u00ednica Dental Bucalis comptem amb els \u00faltims aven\u00e7os tecnol\u00f2gics a les nostres instal\u00b7lacions, que permeten als nostres especialistes en est\u00e8tica dental aplicar les t\u00e8cniques m\u00e9s innovadores com el Disseny Digital de Somriure.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Que_es_el_Disseny_Digital_de_Somriure\"><\/span>Qu\u00e8 \u00e9s el Disseny Digital de Somriure?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>El Disseny Digital de Somriure \u00e9s un Programari capa\u00e7 de generar de forma digital i per mitj\u00e0 d&#8217;un esc\u00e0ner el somriure del pacient. Un cop digitalitzada la boca del pacient, ell mateix al costat del dentista poden triar la forma, color i resultat final que desitja en la seva boca al final del tractament.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/#Que_es_el_Disseny_Digital_de_Somriure\" >Qu\u00e8 \u00e9s el Disseny Digital de Somriure?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/#Com_funciona_el_Disseny_Digital_de_Somriure\" >Com funciona el Disseny Digital de Somriure?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/#Quins_avantatges_aporta_el_Disseny_Digital_de_Somriure\" >Quins avantatges aporta el Disseny Digital de Somriure?<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>\u00c9s canviar la posici\u00f3, la mida, la forma i el color de les dents amb diferents t\u00e8cniques i materials segons el cas, i modificar l&#8217;altura de les genives, creant harmonia amb els llavis, el color de la pell i la forma de la cara . Interv\u00e9 una o diverses especialitats de l&#8217;odontologia i t\u00e8cniques (ortod\u00f2ncia, implants, disseny de genives, blanquejament dental &#8230;).<\/p>\n<p>La possibilitat de veure els resultats del tractament fins i tot abans de comen\u00e7ar-genera una important sensaci\u00f3 de confian\u00e7a i seguretat.<\/p>\n<p>El Disseny de Somriure resulta de gran ajuda tant a l&#8217;odont\u00f2leg, com al pacient, com a t\u00e8cnic de laboratori.<\/p>\n<p>&#8211; Permet dur a terme una planificaci\u00f3 del disseny i l&#8217;est\u00e8tica del somriure millor.<br \/>\n&#8211; Facilita la comunicaci\u00f3 odont\u00f2leg-pacient abans i durant el tractament.<\/p>\n<p>La principal aplicaci\u00f3 del programari de Disseny Digital de Somriure es realitza en tractaments d&#8217;est\u00e8tica dental, per\u00f2 gr\u00e0cies als seus avantatges tamb\u00e9 s&#8217;esta emprant en altres tractaments com implants dentals o ortod\u00f2ncia.<\/p>\n<h2><img decoding=\"async\" class=\"lazyload aligncenter size-full wp-image-3084\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27900%27%20height%3D%27250%27%20viewBox%3D%270%200%20900%20250%27%3E%3Crect%20width%3D%27900%27%20height%3D%27250%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/slider3-1.jpg\" alt=\"Com funciona el Disseny Digital de Somriure?\" width=\"900\" height=\"250\"><br \/>\nCom funciona el Disseny Digital de Somriure?<\/h2>\n<p>A la Cl\u00ednica Dental Bucalis el Disseny Digital de Somriure ens permet desenvolupar una planificaci\u00f3 personalitzada del tractament del pacient mitjan\u00e7ant un estudi fotogr\u00e0fic de la boca i faccions de la cara s&#8217;introdueix tota la informaci\u00f3 sobre el pacient en el Programari.<\/p>\n<p>A partir d&#8217;aqu\u00ed, l&#8217;especialista en est\u00e8tica dental realitza els ajustos sobre la imatge de l&#8217;ordinador veient els resultats directament en la imatge real del pacient.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quins_avantatges_aporta_el_Disseny_Digital_de_Somriure\"><\/span>Quins avantatges aporta el Disseny Digital de Somriure?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Sens dubte \u00e9s una eina que aporta grans avantatges al nostre equip. A m\u00e9s la possibilitat que el pacient pugui veure el resultat final abans de comen\u00e7ar el tractament genera unes expectatives reals, i permet transmetre al dentista seus desitjos de manera m\u00e9s clara.<\/p>\n<p>Aix\u00f2 \u00e9s possible gr\u00e0cies a les diferents funcionalitats que aporta el programari de disseny digital de somriure:<\/p>\n<p style=\"padding-left: 30px;\">1. Possibilitat de combinar diferents tractaments.<br \/>\n2. Considerem l&#8217;est\u00e8tica i l&#8217;estructura de tota la cara.<br \/>\n3. Completament fet a mida per a tu.<br \/>\n4. Vam aconseguir resultats realistes i de llarga durada.<br \/>\n5. Podem aconseguir-te el somriure que sempre has volgut.<\/p>\n<p>El nostre servei de disseny del somriure, gira entorn a tu i a la transformaci\u00f3 del teu somriure al seu m\u00e0xim potencial.<\/p>\n<p>Els nostres dentistes amb tota la seva destresa i afecte s\u00f3n capa\u00e7os de crear millores excel\u00b7lents usant una \u00e0mplia gamma de tractaments d&#8217;est\u00e8tica dental, ortod\u00f2ncia i implants dentals.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la Cl\u00ednica Dental Bucalis any a any observem que  [&#8230;]<\/p>\n","protected":false},"author":8,"featured_media":3103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[56,74],"tags":[],"class_list":["post-4223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sense-categoria","category-tractaments-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges? - Cl\u00ednica dental Oliver Coll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges? - Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"og:description\" content=\"A la Cl\u00ednica Dental Bucalis any a any observem que [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClinicaOliverColl\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-30T11:55:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T16:02:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olivercoll.staging.dissenyweb.com\/wp-content\/uploads\/2026\/01\/diseno-digital-sonrisa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"491\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pilar Oliver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pilar Oliver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/\"},\"author\":{\"name\":\"Pilar Oliver\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\"},\"headline\":\"Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges?\",\"datePublished\":\"2018-01-30T11:55:46+00:00\",\"dateModified\":\"2026-02-27T16:02:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/\"},\"wordCount\":647,\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/diseno-digital-sonrisa.jpg\",\"articleSection\":{\"1\":\"Tractaments\"},\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/\",\"name\":\"Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges? - Cl\u00ednica dental Oliver Coll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/diseno-digital-sonrisa.jpg\",\"datePublished\":\"2018-01-30T11:55:46+00:00\",\"dateModified\":\"2026-02-27T16:02:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/diseno-digital-sonrisa.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/diseno-digital-sonrisa.jpg\",\"width\":700,\"height\":491},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"description\":\"Cl\u00ednica dental en Matar\u00f3\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"width\":300,\"height\":300,\"caption\":\"Cl\u00ednica dental Oliver Coll\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ClinicaOliverColl\",\"https:\\\/\\\/www.instagram.com\\\/clinicaolivercoll\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\",\"name\":\"Pilar Oliver\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"caption\":\"Pilar Oliver\"},\"description\":\"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/author\\\/pilar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges? - Cl\u00ednica dental Oliver Coll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/","og_locale":"ca_ES","og_type":"article","og_title":"Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges? - Cl\u00ednica dental Oliver Coll","og_description":"A la Cl\u00ednica Dental Bucalis any a any observem que [...]","og_url":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/","og_site_name":"Cl\u00ednica dental Oliver Coll","article_publisher":"https:\/\/www.facebook.com\/ClinicaOliverColl","article_published_time":"2018-01-30T11:55:46+00:00","article_modified_time":"2026-02-27T16:02:04+00:00","og_image":[{"width":700,"height":491,"url":"https:\/\/olivercoll.staging.dissenyweb.com\/wp-content\/uploads\/2026\/01\/diseno-digital-sonrisa.jpg","type":"image\/jpeg"}],"author":"Pilar Oliver","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Pilar Oliver","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/#article","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/"},"author":{"name":"Pilar Oliver","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a"},"headline":"Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges?","datePublished":"2018-01-30T11:55:46+00:00","dateModified":"2026-02-27T16:02:04+00:00","mainEntityOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/"},"wordCount":647,"publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/01\/diseno-digital-sonrisa.jpg","articleSection":{"1":"Tractaments"},"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/","url":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/","name":"Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges? - Cl\u00ednica dental Oliver Coll","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/#primaryimage"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/01\/diseno-digital-sonrisa.jpg","datePublished":"2018-01-30T11:55:46+00:00","dateModified":"2026-02-27T16:02:04+00:00","breadcrumb":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/#primaryimage","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/01\/diseno-digital-sonrisa.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/01\/diseno-digital-sonrisa.jpg","width":700,"height":491},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/que-es-el-disseny-digital-de-somriure-i-quins-son-els-seus-avantatges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadentalolivercoll.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e8 \u00e9s el Disseny Digital de Somriure i quins s\u00f3n els seus avantatges?"}]},{"@type":"WebSite","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","name":"Cl\u00ednica dental Oliver Coll","description":"Cl\u00ednica dental en Matar\u00f3","publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadentalolivercoll.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization","name":"Cl\u00ednica dental Oliver Coll","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","width":300,"height":300,"caption":"Cl\u00ednica dental Oliver Coll"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClinicaOliverColl","https:\/\/www.instagram.com\/clinicaolivercoll\/"]},{"@type":"Person","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a","name":"Pilar Oliver","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","caption":"Pilar Oliver"},"description":"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente","url":"https:\/\/clinicadentalolivercoll.com\/ca\/author\/pilar\/"}]}},"_links":{"self":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/comments?post=4223"}],"version-history":[{"count":0,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/media\/3103"}],"wp:attachment":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/media?parent=4223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/categories?post=4223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/tags?post=4223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}