{"id":4110,"date":"2016-11-04T02:31:54","date_gmt":"2016-11-04T02:31:54","guid":{"rendered":"https:\/\/olivercoll.staging.dissenyweb.com\/a-que-es-deguda-la-sensibilitat-dental\/"},"modified":"2026-02-27T16:02:02","modified_gmt":"2026-02-27T16:02:02","slug":"a-que-es-deguda-la-sensibilitat-dental","status":"publish","type":"post","link":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/","title":{"rendered":"A que \u00e9s deguda la sensibilitat dental?"},"content":{"rendered":"<p><a href=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2016\/05\/Remedio-casero-para-el-dolor-de-muelas-1.jpg\"><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-2073\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271260%27%20height%3D%27840%27%20viewBox%3D%270%200%201260%20840%27%3E%3Crect%20width%3D%271260%27%20height%3D%27840%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/Remedio-casero-para-el-dolor-de-muelas-1.jpg\" alt=\"Sensibilidad Dental\" width=\"1260\" height=\"840\"><\/a><br \/>\nLa sensibilitat dental, generalment, \u00e9s causada per menjar o beure alguna cosa calenta, fred, dol\u00e7 o \u00e0cid. En condicions normals, la dentina subjacent de la dent (la capa que envolta directament el nervi) est\u00e0 coberta per l&#8217;esmalt i les genives que envolten la dent. Amb el temps, el recobriment d&#8217;esmalt pot fer-se m\u00e9s prim, proporcionant aix\u00ed menys protecci\u00f3.<\/p>\n<p><!--more--><\/p>\n<p>Les genives poden retreure amb el pas del temps, exposant la superf\u00edcie de l&#8217;arrel subjacent de la dentina. La dentina cont\u00e9 una gran quantitat de porus o conductes que corren des de la part exterior de la dent cap al nervi al centre. Quan la dentina es troba exposada aquests conductes poden ser estimulats per canvis de temperatura o certs aliments<\/p>\n<p>La sensibilitat dental influeix en la qualitat de vida de les persones que la pateixen. Si pateix sensibilitat dental el m\u00e9s aconsellable \u00e9s acudir al seu odont\u00f2leg de confian\u00e7a, perqu\u00e8 pugui fer-li un diagn\u00f2stic exhaustiu i programar-un tractament adequat. A continuaci\u00f3 expliquem com evitar la sensibilitat dental amb aquests senzills consells:<\/p>\n<ol>\n<li>Controlar el consum d&#8217;aliments \u00e0cids, ja que poden desgastar l&#8217;esmalt i la dentina pot arribar a quedar al descobert, especialment si es realitza el raspallat just despr\u00e9s de la seva ingesta.<\/li>\n<li>Corregir mals h\u00e0bits com, tallar el fil amb les dents, obrir envasos amb la boca, deixar de fumar, etc ..<\/li>\n<li>Mantenir la const\u00e0ncia en l&#8217;\u00fas de productes espec\u00edfics per a combatre la sensibilitat dental: utilitzar un raspall amb filaments suaus, una pasta de dents espec\u00edfica i un col\u00b7lutori per dents sensibles. La rutina del raspallat tamb\u00e9 \u00e9s important, ja que raspallar amb massa for\u00e7a o freq\u00fc\u00e8ncia o amb un raspall poc adequat podria provocar sensibilitat dental a llarg termini.<\/li>\n<li>Tractar el bruxisme. Si les dents grinyolen quan dormim o els estrenyem durant el dia, l&#8217;esmalt es desgasta i la dentina pot quedar exposada.<\/li>\n<li>Acudir a revisions peri\u00f2diques al dentista: Es recomana realitzar una higiene bucal per professionals cada 6 mesos \/ 1 any, depenent de cada persona, \u00e9s a dir, no nom\u00e9s anar al dentista quan sentis dolor, sin\u00f3 per prevenir futurs inconvenients.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>La sensibilitat dental, generalment, \u00e9s causada per menjar o beure  [&#8230;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[56,74],"tags":[],"class_list":["post-4110","post","type-post","status-publish","format-standard","hentry","category-sense-categoria","category-tractaments-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A que \u00e9s deguda la sensibilitat dental? - Cl\u00ednica dental Oliver Coll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A que \u00e9s deguda la sensibilitat dental? - Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"og:description\" content=\"La sensibilitat dental, generalment, \u00e9s causada per menjar o beure [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClinicaOliverColl\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-04T02:31:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T16:02:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/Remedio-casero-para-el-dolor-de-muelas-1.jpg\" \/>\n<meta name=\"author\" content=\"Pilar Oliver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pilar Oliver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/\"},\"author\":{\"name\":\"Pilar Oliver\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\"},\"headline\":\"A que \u00e9s deguda la sensibilitat dental?\",\"datePublished\":\"2016-11-04T02:31:54+00:00\",\"dateModified\":\"2026-02-27T16:02:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/\"},\"wordCount\":370,\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Remedio-casero-para-el-dolor-de-muelas-1.jpg\",\"articleSection\":{\"1\":\"Tractaments\"},\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/\",\"name\":\"A que \u00e9s deguda la sensibilitat dental? - Cl\u00ednica dental Oliver Coll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Remedio-casero-para-el-dolor-de-muelas-1.jpg\",\"datePublished\":\"2016-11-04T02:31:54+00:00\",\"dateModified\":\"2026-02-27T16:02:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Remedio-casero-para-el-dolor-de-muelas-1.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Remedio-casero-para-el-dolor-de-muelas-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/a-que-es-deguda-la-sensibilitat-dental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A que \u00e9s deguda la sensibilitat dental?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"description\":\"Cl\u00ednica dental en Matar\u00f3\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"width\":300,\"height\":300,\"caption\":\"Cl\u00ednica dental Oliver Coll\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ClinicaOliverColl\",\"https:\\\/\\\/www.instagram.com\\\/clinicaolivercoll\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\",\"name\":\"Pilar Oliver\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"caption\":\"Pilar Oliver\"},\"description\":\"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/author\\\/pilar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A que \u00e9s deguda la sensibilitat dental? - Cl\u00ednica dental Oliver Coll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/","og_locale":"ca_ES","og_type":"article","og_title":"A que \u00e9s deguda la sensibilitat dental? - Cl\u00ednica dental Oliver Coll","og_description":"La sensibilitat dental, generalment, \u00e9s causada per menjar o beure [...]","og_url":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/","og_site_name":"Cl\u00ednica dental Oliver Coll","article_publisher":"https:\/\/www.facebook.com\/ClinicaOliverColl","article_published_time":"2016-11-04T02:31:54+00:00","article_modified_time":"2026-02-27T16:02:02+00:00","og_image":[{"url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/Remedio-casero-para-el-dolor-de-muelas-1.jpg","type":"","width":"","height":""}],"author":"Pilar Oliver","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Pilar Oliver","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/#article","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/"},"author":{"name":"Pilar Oliver","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a"},"headline":"A que \u00e9s deguda la sensibilitat dental?","datePublished":"2016-11-04T02:31:54+00:00","dateModified":"2026-02-27T16:02:02+00:00","mainEntityOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/"},"wordCount":370,"publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/Remedio-casero-para-el-dolor-de-muelas-1.jpg","articleSection":{"1":"Tractaments"},"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/","url":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/","name":"A que \u00e9s deguda la sensibilitat dental? - Cl\u00ednica dental Oliver Coll","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/#primaryimage"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/Remedio-casero-para-el-dolor-de-muelas-1.jpg","datePublished":"2016-11-04T02:31:54+00:00","dateModified":"2026-02-27T16:02:02+00:00","breadcrumb":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/#primaryimage","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/Remedio-casero-para-el-dolor-de-muelas-1.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/Remedio-casero-para-el-dolor-de-muelas-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/a-que-es-deguda-la-sensibilitat-dental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadentalolivercoll.com\/ca\/"},{"@type":"ListItem","position":2,"name":"A que \u00e9s deguda la sensibilitat dental?"}]},{"@type":"WebSite","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","name":"Cl\u00ednica dental Oliver Coll","description":"Cl\u00ednica dental en Matar\u00f3","publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadentalolivercoll.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization","name":"Cl\u00ednica dental Oliver Coll","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","width":300,"height":300,"caption":"Cl\u00ednica dental Oliver Coll"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClinicaOliverColl","https:\/\/www.instagram.com\/clinicaolivercoll\/"]},{"@type":"Person","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a","name":"Pilar Oliver","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","caption":"Pilar Oliver"},"description":"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente","url":"https:\/\/clinicadentalolivercoll.com\/ca\/author\/pilar\/"}]}},"_links":{"self":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/comments?post=4110"}],"version-history":[{"count":0,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4110\/revisions"}],"wp:attachment":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/media?parent=4110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/categories?post=4110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/tags?post=4110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}