{"id":4108,"date":"2016-11-04T02:30:25","date_gmt":"2016-11-04T02:30:25","guid":{"rendered":"https:\/\/olivercoll.staging.dissenyweb.com\/el-tractament-invisalign-proporciona-molts-beneficis\/"},"modified":"2026-02-27T16:02:03","modified_gmt":"2026-02-27T16:02:03","slug":"el-tractament-invisalign-proporciona-molts-beneficis","status":"publish","type":"post","link":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/","title":{"rendered":"El tractament Invisalign proporciona molts beneficis"},"content":{"rendered":"<p>INVISALIGN NO \u00e9s la soluci\u00f3 perfecta per a tots, per\u00f2 si vost\u00e8 \u00e9s un bon candidat, hi ha un munt de raons per triar <a href=\"https:\/\/clinicadentalolivercoll.com\/ca\/serveis\/ortodoncia\/invisalign\/\">Invisalign<\/a>, i no nom\u00e9s per no portar ferros!<br \/>\nTransparents, les ferulas extra\u00efbles d&#8217;Invisalign s\u00f3n un m\u00e8tode de tractament d&#8217;ortod\u00f2ncia menys invasiva. Amb la tecnologia Invisalign, les dents es poden redre\u00e7ar sense causar inconvenients a la seva vida di\u00e0ria<\/p>\n<div id=\"attachment_1714\" style=\"width: 340px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2014\/12\/image3.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1714\" class=\"lazyload wp-image-1714\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27330%27%20height%3D%27338%27%20viewBox%3D%270%200%20330%20338%27%3E%3Crect%20width%3D%27330%27%20height%3D%27338%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/image3.jpg\" alt=\"Invisalign aligner\" width=\"330\" height=\"338\"><\/a><p id=\"caption-attachment-1714\" class=\"wp-caption-text\">Invisalign aligner<\/p><\/div>\n<p>Els beneficis que vost\u00e8 probablement no esperava<\/p>\n<ul>\n<li>La difer\u00e8ncia m\u00e9s \u00f2bvia entre el tractament amb Invisalign i brackets \u00e9s la seva aparen\u00e7a, per\u00f2 hi ha m\u00e9s que aix\u00f2. Per exemple &#8230;<\/li>\n<li>Menys visites al consultori. Veurem que nom\u00e9s un cop cada 4 a 6 setmanes.<br \/>\nLes ferulas d&#8217;Invisalign a vegades les pot fer servir com ferulas de blanquejament o de protecci\u00f3 per als esports.<\/li>\n<li>Les ferulas extra\u00efbles li permeten raspallar-se les dents normalment, el que resulta una millor salut bucal durant el tractament.<\/li>\n<li>Vost\u00e8 pot gaudir dels aliments que tri\u00ef, sense les restriccions en la dieta dels brackets.<\/li>\n<li>Les ferulas de pl\u00e0stic llises s\u00f3n m\u00e9s c\u00f2modes, per la qual cosa no es tindr\u00e0 de preocupar de la irritaci\u00f3 que de vegades causen els brackets.<\/li>\n<\/ul>\n<p>Els nostres pacients m\u00e9s ens indiquen que els ajuda a mantenir la silueta ja que deixen de picar entre hores i que mai havien tingut les dents tan blanques ja que ara se&#8217;ls renten despr\u00e9s de cada \u00e0pat.<\/p>\n<p>Les dents rectes i amb una correcta oclusi\u00f3 proporcionen m\u00e9s que una bella aparen\u00e7a.<\/p>\n<p>Deixant de banda l&#8217;est\u00e8tica, tenir les dents rectes \u00e9s important per un diverses raons. Les dents rectes s\u00f3n m\u00e9s f\u00e0cils de netejar i usar fil dental. Tamb\u00e9 protegeixen contra el desgast desigual, i els problemes d&#8217;ATM. Les dents rectes permeten una masticaci\u00f3 m\u00e9s eficient i millorar la digesti\u00f3 dels aliments. Les dents rectes poden fins i tot millorar la pronunciaci\u00f3 i la parla!<\/p>\n<h3>\u00c9s Invisalign adequat per a vost\u00e8?<\/h3>\n<p>Programame una cita gratu\u00efta amb la Dra. Gr\u00e0cia! Ens encantaria veure el que podem fer per millorar i preservar la seva bella somriure. Gr\u00e0cies per endavant per la seva confian\u00e7a. Esperem veure&#8217;l aviat!<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>INVISALIGN NO \u00e9s la soluci\u00f3 perfecta per a tots, per\u00f2  [&#8230;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[56,74],"tags":[],"class_list":["post-4108","post","type-post","status-publish","format-standard","hentry","category-sense-categoria","category-tractaments-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El tractament Invisalign proporciona molts beneficis - Cl\u00ednica dental Oliver Coll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El tractament Invisalign proporciona molts beneficis - Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"og:description\" content=\"INVISALIGN NO \u00e9s la soluci\u00f3 perfecta per a tots, per\u00f2 [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClinicaOliverColl\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-04T02:30:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T16:02:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/image3.jpg\" \/>\n<meta name=\"author\" content=\"Pilar Oliver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pilar Oliver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/\"},\"author\":{\"name\":\"Pilar Oliver\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\"},\"headline\":\"El tractament Invisalign proporciona molts beneficis\",\"datePublished\":\"2016-11-04T02:30:25+00:00\",\"dateModified\":\"2026-02-27T16:02:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/\"},\"wordCount\":389,\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/image3.jpg\",\"articleSection\":{\"1\":\"Tractaments\"},\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/\",\"name\":\"El tractament Invisalign proporciona molts beneficis - Cl\u00ednica dental Oliver Coll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/image3.jpg\",\"datePublished\":\"2016-11-04T02:30:25+00:00\",\"dateModified\":\"2026-02-27T16:02:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/image3.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/image3.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/el-tractament-invisalign-proporciona-molts-beneficis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El tractament Invisalign proporciona molts beneficis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"description\":\"Cl\u00ednica dental en Matar\u00f3\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"width\":300,\"height\":300,\"caption\":\"Cl\u00ednica dental Oliver Coll\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ClinicaOliverColl\",\"https:\\\/\\\/www.instagram.com\\\/clinicaolivercoll\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\",\"name\":\"Pilar Oliver\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"caption\":\"Pilar Oliver\"},\"description\":\"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/author\\\/pilar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El tractament Invisalign proporciona molts beneficis - Cl\u00ednica dental Oliver Coll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/","og_locale":"ca_ES","og_type":"article","og_title":"El tractament Invisalign proporciona molts beneficis - Cl\u00ednica dental Oliver Coll","og_description":"INVISALIGN NO \u00e9s la soluci\u00f3 perfecta per a tots, per\u00f2 [...]","og_url":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/","og_site_name":"Cl\u00ednica dental Oliver Coll","article_publisher":"https:\/\/www.facebook.com\/ClinicaOliverColl","article_published_time":"2016-11-04T02:30:25+00:00","article_modified_time":"2026-02-27T16:02:03+00:00","og_image":[{"url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/image3.jpg","type":"","width":"","height":""}],"author":"Pilar Oliver","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Pilar Oliver","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/#article","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/"},"author":{"name":"Pilar Oliver","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a"},"headline":"El tractament Invisalign proporciona molts beneficis","datePublished":"2016-11-04T02:30:25+00:00","dateModified":"2026-02-27T16:02:03+00:00","mainEntityOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/"},"wordCount":389,"publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/image3.jpg","articleSection":{"1":"Tractaments"},"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/","url":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/","name":"El tractament Invisalign proporciona molts beneficis - Cl\u00ednica dental Oliver Coll","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/#primaryimage"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/image3.jpg","datePublished":"2016-11-04T02:30:25+00:00","dateModified":"2026-02-27T16:02:03+00:00","breadcrumb":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/#primaryimage","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/image3.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/image3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/el-tractament-invisalign-proporciona-molts-beneficis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadentalolivercoll.com\/ca\/"},{"@type":"ListItem","position":2,"name":"El tractament Invisalign proporciona molts beneficis"}]},{"@type":"WebSite","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","name":"Cl\u00ednica dental Oliver Coll","description":"Cl\u00ednica dental en Matar\u00f3","publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadentalolivercoll.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization","name":"Cl\u00ednica dental Oliver Coll","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","width":300,"height":300,"caption":"Cl\u00ednica dental Oliver Coll"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClinicaOliverColl","https:\/\/www.instagram.com\/clinicaolivercoll\/"]},{"@type":"Person","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a","name":"Pilar Oliver","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","caption":"Pilar Oliver"},"description":"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente","url":"https:\/\/clinicadentalolivercoll.com\/ca\/author\/pilar\/"}]}},"_links":{"self":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/comments?post=4108"}],"version-history":[{"count":0,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4108\/revisions"}],"wp:attachment":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/media?parent=4108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/categories?post=4108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/tags?post=4108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}