{"id":4103,"date":"2016-11-04T02:23:13","date_gmt":"2016-11-04T02:23:13","guid":{"rendered":"https:\/\/olivercoll.staging.dissenyweb.com\/oferta-invisalign-a-jornada-portes-obertes\/"},"modified":"2026-02-27T16:02:04","modified_gmt":"2026-02-27T16:02:04","slug":"oferta-invisalign-a-jornada-portes-obertes","status":"publish","type":"post","link":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/","title":{"rendered":"Oferta Invisalign a Jornada Portes Obertes"},"content":{"rendered":"<h1><a href=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2016\/05\/invislign-ortodoncia-invisible.jpg\"><img decoding=\"async\" class=\"lazyload alignnone wp-image-2118\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27594%27%20height%3D%27156%27%20viewBox%3D%270%200%20594%20156%27%3E%3Crect%20width%3D%27594%27%20height%3D%27156%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/invislign-ortodoncia-invisible.jpg\" alt=\"invislign-ortodoncia-invisible\" width=\"594\" height=\"156\"><\/a><\/h1>\n<p>El proper 1 de juny portes obertes <a href=\"https:\/\/clinicadentalolivercoll.com\/ca\/serveis\/ortodoncia\/invisalign\/\">INVISALIGN<\/a>, l&#8217;ortod\u00f2ncia invisible sense brackets.<\/p>\n<p>Si aquest dia comences el tractament et benefici\u00e0ries d&#8217;una super oferta (veure taula).<\/p>\n<p>Nom\u00e9s has de reservar la teva cita per tel\u00e8fon 93 741 40 06. Pots venir acompanyat de qui tu vulguis.<\/p>\n<p>Bucalis obsequiar\u00e0 a tots els seus visitants amb:<\/p>\n<ul>\n<li>Revisi\u00f3 i radiografia bucal.<\/li>\n<li>Informaci\u00f3 sobre el tractament i podr\u00e0s veure l&#8217;abans i despr\u00e9s amb INVISALIGN en una simulaci\u00f3 3D d&#8217;un cas amb complexitat similar a la teva<\/li>\n<\/ul>\n<table>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" width=\"189\">Invisalign I7 (3 mesos de tractament aprox)<\/td>\n<td width=\"189\">Invisalign Lite (7 mesos tractament\u00a0aprox)<\/td>\n<td width=\"189\">Invisalign Full\/Teen (10 mesos en endavant)<\/td>\n<\/tr>\n<tr>\n<td width=\"189\">Descompte 190\u20ac.<\/td>\n<td width=\"189\">Descompte 370\u20ac.<\/td>\n<td width=\"189\">Descompte 500\u20ac.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proper 1 de juny portes obertes INVISALIGN, l&#8217;ortod\u00f2ncia invisible  [&#8230;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[83,56],"tags":[],"class_list":["post-4103","post","type-post","status-publish","format-standard","hentry","category-events-ca","category-sense-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oferta Invisalign a Jornada Portes Obertes - Cl\u00ednica dental Oliver Coll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oferta Invisalign a Jornada Portes Obertes - Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"og:description\" content=\"El proper 1 de juny portes obertes INVISALIGN, l&#8217;ortod\u00f2ncia invisible [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClinicaOliverColl\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-04T02:23:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T16:02:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/invislign-ortodoncia-invisible.jpg\" \/>\n<meta name=\"author\" content=\"Pilar Oliver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pilar Oliver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/\"},\"author\":{\"name\":\"Pilar Oliver\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\"},\"headline\":\"Oferta Invisalign a Jornada Portes Obertes\",\"datePublished\":\"2016-11-04T02:23:13+00:00\",\"dateModified\":\"2026-02-27T16:02:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/\"},\"wordCount\":112,\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/invislign-ortodoncia-invisible.jpg\",\"articleSection\":[\"Events\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/\",\"name\":\"Oferta Invisalign a Jornada Portes Obertes - Cl\u00ednica dental Oliver Coll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/invislign-ortodoncia-invisible.jpg\",\"datePublished\":\"2016-11-04T02:23:13+00:00\",\"dateModified\":\"2026-02-27T16:02:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/invislign-ortodoncia-invisible.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/invislign-ortodoncia-invisible.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/oferta-invisalign-a-jornada-portes-obertes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oferta Invisalign a Jornada Portes Obertes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"description\":\"Cl\u00ednica dental en Matar\u00f3\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"width\":300,\"height\":300,\"caption\":\"Cl\u00ednica dental Oliver Coll\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ClinicaOliverColl\",\"https:\\\/\\\/www.instagram.com\\\/clinicaolivercoll\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\",\"name\":\"Pilar Oliver\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"caption\":\"Pilar Oliver\"},\"description\":\"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/author\\\/pilar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oferta Invisalign a Jornada Portes Obertes - Cl\u00ednica dental Oliver Coll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/","og_locale":"ca_ES","og_type":"article","og_title":"Oferta Invisalign a Jornada Portes Obertes - Cl\u00ednica dental Oliver Coll","og_description":"El proper 1 de juny portes obertes INVISALIGN, l&#8217;ortod\u00f2ncia invisible [...]","og_url":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/","og_site_name":"Cl\u00ednica dental Oliver Coll","article_publisher":"https:\/\/www.facebook.com\/ClinicaOliverColl","article_published_time":"2016-11-04T02:23:13+00:00","article_modified_time":"2026-02-27T16:02:04+00:00","og_image":[{"url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/invislign-ortodoncia-invisible.jpg","type":"","width":"","height":""}],"author":"Pilar Oliver","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Pilar Oliver","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/#article","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/"},"author":{"name":"Pilar Oliver","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a"},"headline":"Oferta Invisalign a Jornada Portes Obertes","datePublished":"2016-11-04T02:23:13+00:00","dateModified":"2026-02-27T16:02:04+00:00","mainEntityOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/"},"wordCount":112,"publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/invislign-ortodoncia-invisible.jpg","articleSection":["Events"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/","url":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/","name":"Oferta Invisalign a Jornada Portes Obertes - Cl\u00ednica dental Oliver Coll","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/#primaryimage"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/invislign-ortodoncia-invisible.jpg","datePublished":"2016-11-04T02:23:13+00:00","dateModified":"2026-02-27T16:02:04+00:00","breadcrumb":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/#primaryimage","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/invislign-ortodoncia-invisible.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/invislign-ortodoncia-invisible.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/oferta-invisalign-a-jornada-portes-obertes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadentalolivercoll.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Oferta Invisalign a Jornada Portes Obertes"}]},{"@type":"WebSite","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","name":"Cl\u00ednica dental Oliver Coll","description":"Cl\u00ednica dental en Matar\u00f3","publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadentalolivercoll.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization","name":"Cl\u00ednica dental Oliver Coll","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","width":300,"height":300,"caption":"Cl\u00ednica dental Oliver Coll"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClinicaOliverColl","https:\/\/www.instagram.com\/clinicaolivercoll\/"]},{"@type":"Person","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a","name":"Pilar Oliver","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","caption":"Pilar Oliver"},"description":"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente","url":"https:\/\/clinicadentalolivercoll.com\/ca\/author\/pilar\/"}]}},"_links":{"self":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/comments?post=4103"}],"version-history":[{"count":0,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4103\/revisions"}],"wp:attachment":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/media?parent=4103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/categories?post=4103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/tags?post=4103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}