{"id":4097,"date":"2016-11-04T02:07:41","date_gmt":"2016-11-04T02:07:41","guid":{"rendered":"https:\/\/olivercoll.staging.dissenyweb.com\/consequencies-del-tabac\/"},"modified":"2026-02-27T16:02:03","modified_gmt":"2026-02-27T16:02:03","slug":"consequencies-del-tabac","status":"publish","type":"post","link":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/","title":{"rendered":"Conseq\u00fc\u00e8ncies del Tabac"},"content":{"rendered":"<p><a href=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2016\/04\/dia-mundial-sin-tabaco.jpg\"><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-1994\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27625%27%20height%3D%27366%27%20viewBox%3D%270%200%20625%20366%27%3E%3Crect%20width%3D%27625%27%20height%3D%27366%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/dia-mundial-sin-tabaco.jpg\" alt=\"El Tabaco y sus consecuencias\" width=\"625\" height=\"366\"><\/a><br \/>\n\u00a0<\/p>\n<p>El tabaquisme \u00e9s un <strong>h\u00e0bit perjudicial<\/strong> per a la salut que continua estant molt present en la poblaci\u00f3 en general, sobretot en els pa\u00efsos en desenvolupament. El consum de tabac es relaciona amb una <strong>llarga llista de malalties i alteracions sist\u00e8miques<\/strong>, i entre elles diverses que afecten la salut oral.<br \/>\n<!--more--><\/p>\n<p>El fum irrita les mucoses orals i la nicotina t\u00e9 efectes directes sobre les genives. Un clar exemple d&#8217;aquestes alteracions \u00e9s el retard en la cicatritzaci\u00f3 de ferides de la boca. A m\u00e9s, fumar pot produir mal al\u00e8, per l&#8217;olor en si del tabac i per variacions de la microbiota bacteriana de la boca.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/#Tabac_i_malaltia_periodontal\" >Tabac i malaltia periodontal<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/#Tabac_i_cancer_oral\" >Tabac i c\u00e0ncer oral<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>De tota manera, les principals malalties orals associades al consum de tabac i s\u00f3n la <strong>malaltia periodontal i el c\u00e0ncer oral<\/strong>.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Tabac_i_malaltia_periodontal\"><\/span>Tabac i malaltia periodontal<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El tabac augmenta de 5 a 20 vegades el risc de patir una malaltia periodontal. La caracter\u00edstica t\u00edpica de la malaltia periodontal associada al tabac \u00e9s la destrucci\u00f3 dels teixits de suport de les dents, amb els signes derivats de la p\u00e8rdua d&#8217;os, formaci\u00f3 de bosses periodontals i, ocasionalment, p\u00e8rdua dental.<\/p>\n<p>Els fumadors amb periodontitis responen menys favorablement als tractaments periodontals, tant no quir\u00fargics com quir\u00fargics, i no s&#8217;aconsellen cirurgies de tipus regeneratiu i mucogingival.<\/p>\n<p>A m\u00e9s, els fumadors tenen m\u00e9s risc de patir complicacions amb els implants dentals, tant a curt com a llarg termini.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Tabac_i_cancer_oral\"><\/span>Tabac i c\u00e0ncer oral<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El tabac juntament amb la ingesti\u00f3 d&#8217;alcohol i certes defici\u00e8ncies nutricionals d&#8217;alguns micronutrients s\u00f3n la principal causa de c\u00e0ncer oral.<\/p>\n<p>El tabac cont\u00e9 al voltant de m\u00e9s de 60 productes de combusti\u00f3 carcin\u00f2gens amb capacitat per unir-se a l&#8217;ADN i alterar-lo. A m\u00e9s, aquest augmenta l&#8217;estr\u00e8s oxidatiu<br \/>\ndels teixits i, per tant, l&#8217;alliberament d&#8217;esp\u00e8cies de radicals lliures que danyen les prote\u00efnes, l\u00edpids, carbohidrats i el mateix ADN.<\/p>\n<p>Els estudis demostren que el risc de patir c\u00e0ncer oral en fumadors supera de tres a cinc vegades els no fumadors, que l&#8217;efecte \u00e9s dosi-depenent i que aix\u00f2 es multiplica de forma dram\u00e0tica juntament amb la ingesti\u00f3 d&#8217;alcohol.<\/p>\n<p>Per tant, \u00e9s molt important con\u00e8ixer quins poden ser els efectes del tabac tant en la salut bucodental com en la salut en general. Si s&#8217;\u00e9s fumador o s&#8217;acaba de deixar de fumar, \u00e9s molt recomanable acudir al seu odont\u00f2leg de confian\u00e7a per poder realitzar un diagn\u00f2stic complet de l&#8217;estat de la seva boca. I aix\u00ed, poder realitzar un tractament personalitzat d&#8217;acord amb les necessitats de cada un.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 El tabaquisme \u00e9s un h\u00e0bit perjudicial per a la  [&#8230;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[56,74],"tags":[118,213,271],"class_list":["post-4097","post","type-post","status-publish","format-standard","hentry","category-sense-categoria","category-tractaments-ca","tag-causes-ca","tag-malalties-ca","tag-tabac-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conseq\u00fc\u00e8ncies del Tabac - Cl\u00ednica dental Oliver Coll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseq\u00fc\u00e8ncies del Tabac - Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"og:description\" content=\"\u00a0 El tabaquisme \u00e9s un h\u00e0bit perjudicial per a la [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClinicaOliverColl\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-04T02:07:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T16:02:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/dia-mundial-sin-tabaco.jpg\" \/>\n<meta name=\"author\" content=\"Pilar Oliver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pilar Oliver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/\"},\"author\":{\"name\":\"Pilar Oliver\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\"},\"headline\":\"Conseq\u00fc\u00e8ncies del Tabac\",\"datePublished\":\"2016-11-04T02:07:41+00:00\",\"dateModified\":\"2026-02-27T16:02:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/\"},\"wordCount\":450,\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/dia-mundial-sin-tabaco.jpg\",\"keywords\":[\"Causes\",\"Malalties\",\"Tabac\"],\"articleSection\":{\"1\":\"Tractaments\"},\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/\",\"name\":\"Conseq\u00fc\u00e8ncies del Tabac - Cl\u00ednica dental Oliver Coll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/dia-mundial-sin-tabaco.jpg\",\"datePublished\":\"2016-11-04T02:07:41+00:00\",\"dateModified\":\"2026-02-27T16:02:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/dia-mundial-sin-tabaco.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/dia-mundial-sin-tabaco.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/consequencies-del-tabac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseq\u00fc\u00e8ncies del Tabac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"description\":\"Cl\u00ednica dental en Matar\u00f3\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"width\":300,\"height\":300,\"caption\":\"Cl\u00ednica dental Oliver Coll\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ClinicaOliverColl\",\"https:\\\/\\\/www.instagram.com\\\/clinicaolivercoll\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/person\\\/d6ec68eb102796cdbfbb44f6f705766a\",\"name\":\"Pilar Oliver\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/litespeed\\\/avatar\\\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777\",\"caption\":\"Pilar Oliver\"},\"description\":\"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/author\\\/pilar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conseq\u00fc\u00e8ncies del Tabac - Cl\u00ednica dental Oliver Coll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/","og_locale":"ca_ES","og_type":"article","og_title":"Conseq\u00fc\u00e8ncies del Tabac - Cl\u00ednica dental Oliver Coll","og_description":"\u00a0 El tabaquisme \u00e9s un h\u00e0bit perjudicial per a la [...]","og_url":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/","og_site_name":"Cl\u00ednica dental Oliver Coll","article_publisher":"https:\/\/www.facebook.com\/ClinicaOliverColl","article_published_time":"2016-11-04T02:07:41+00:00","article_modified_time":"2026-02-27T16:02:03+00:00","og_image":[{"url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/dia-mundial-sin-tabaco.jpg","type":"","width":"","height":""}],"author":"Pilar Oliver","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Pilar Oliver","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/#article","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/"},"author":{"name":"Pilar Oliver","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a"},"headline":"Conseq\u00fc\u00e8ncies del Tabac","datePublished":"2016-11-04T02:07:41+00:00","dateModified":"2026-02-27T16:02:03+00:00","mainEntityOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/"},"wordCount":450,"publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/dia-mundial-sin-tabaco.jpg","keywords":["Causes","Malalties","Tabac"],"articleSection":{"1":"Tractaments"},"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/","url":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/","name":"Conseq\u00fc\u00e8ncies del Tabac - Cl\u00ednica dental Oliver Coll","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/#primaryimage"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/#primaryimage"},"thumbnailUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/dia-mundial-sin-tabaco.jpg","datePublished":"2016-11-04T02:07:41+00:00","dateModified":"2026-02-27T16:02:03+00:00","breadcrumb":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/#primaryimage","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/dia-mundial-sin-tabaco.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/02\/dia-mundial-sin-tabaco.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/consequencies-del-tabac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadentalolivercoll.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Conseq\u00fc\u00e8ncies del Tabac"}]},{"@type":"WebSite","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","name":"Cl\u00ednica dental Oliver Coll","description":"Cl\u00ednica dental en Matar\u00f3","publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadentalolivercoll.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization","name":"Cl\u00ednica dental Oliver Coll","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","width":300,"height":300,"caption":"Cl\u00ednica dental Oliver Coll"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClinicaOliverColl","https:\/\/www.instagram.com\/clinicaolivercoll\/"]},{"@type":"Person","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/person\/d6ec68eb102796cdbfbb44f6f705766a","name":"Pilar Oliver","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/litespeed\/avatar\/37652e3a84f3e48f80fa7561f193306d.jpg?ver=1784069777","caption":"Pilar Oliver"},"description":"Diploma en Direcci\u00f3n Odontol\u00f3gica y Gesti\u00f3n Cl\u00ednica Diploma Gerencia en Odontolog\u00eda, Administraci\u00f3n y Marketing Dental Curso de atenci\u00f3n al Paciente","url":"https:\/\/clinicadentalolivercoll.com\/ca\/author\/pilar\/"}]}},"_links":{"self":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/comments?post=4097"}],"version-history":[{"count":0,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/posts\/4097\/revisions"}],"wp:attachment":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/media?parent=4097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/categories?post=4097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/tags?post=4097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}