{"id":7610,"date":"2026-07-10T11:16:39","date_gmt":"2026-07-10T11:16:39","guid":{"rendered":"https:\/\/olivercoll.staging.dissenyweb.com\/faq-items\/com-es-la-primera-visita-amb-el-denista\/"},"modified":"2026-07-10T11:16:39","modified_gmt":"2026-07-10T11:16:39","slug":"com-es-la-primera-visita-amb-el-denista","status":"publish","type":"avada_faq","link":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/com-es-la-primera-visita-amb-el-denista\/","title":{"rendered":"Com \u00e9s la primera visita amb el denista?"},"content":{"rendered":"<p>Des de la teva arribada a la nostra cl\u00ednica, rebr\u00e0s una atenci\u00f3 propera, professional i orientada al teu benestar. En la primera visita a la nostra cl\u00ednica dental a Matar\u00f3, realitzem una entrevista inicial per con\u00e8ixer els teus antecedents m\u00e8dics, les teves expectatives i les teves necessitats concretes. <\/p>\n<p>Posteriorment, duem a terme una revisi\u00f3 completa de la teva salut oral, incloent radiografies i escanejos digitals si \u00e9s necessari. Amb tota aquesta informaci\u00f3 elaborem un pla de tractament personalitzat, que t&#8217;expliquem amb claredat perqu\u00e8 prenguis decisions informades i sense sorpreses. <\/p>\n<p>Volem que la teva primera experi\u00e8ncia amb nosaltres sigui tranquil\u00b7la, clara i totalment satisfact\u00f2ria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des de la teva arribada a la nostra cl\u00ednica, rebr\u00e0s  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"faq_category":[412],"class_list":["post-7610","avada_faq","type-avada_faq","status-publish","format-standard","hentry","faq_category-clinica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Com \u00e9s la primera visita amb el denista? - Cl\u00ednica dental Oliver Coll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/com-es-la-primera-visita-amb-el-denista\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Com \u00e9s la primera visita amb el denista? - Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"og:description\" content=\"Des de la teva arribada a la nostra cl\u00ednica, rebr\u00e0s [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/com-es-la-primera-visita-amb-el-denista\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClinicaOliverColl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/com-es-la-primera-visita-amb-el-denista\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/com-es-la-primera-visita-amb-el-denista\\\/\",\"name\":\"Com \u00e9s la primera visita amb el denista? - Cl\u00ednica dental Oliver Coll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\"},\"datePublished\":\"2026-07-10T11:16:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/com-es-la-primera-visita-amb-el-denista\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/com-es-la-primera-visita-amb-el-denista\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/com-es-la-primera-visita-amb-el-denista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Com \u00e9s la primera visita amb el denista?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"description\":\"Cl\u00ednica dental en Matar\u00f3\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"width\":300,\"height\":300,\"caption\":\"Cl\u00ednica dental Oliver Coll\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ClinicaOliverColl\",\"https:\\\/\\\/www.instagram.com\\\/clinicaolivercoll\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Com \u00e9s la primera visita amb el denista? - Cl\u00ednica dental Oliver Coll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/com-es-la-primera-visita-amb-el-denista\/","og_locale":"ca_ES","og_type":"article","og_title":"Com \u00e9s la primera visita amb el denista? - Cl\u00ednica dental Oliver Coll","og_description":"Des de la teva arribada a la nostra cl\u00ednica, rebr\u00e0s [...]","og_url":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/com-es-la-primera-visita-amb-el-denista\/","og_site_name":"Cl\u00ednica dental Oliver Coll","article_publisher":"https:\/\/www.facebook.com\/ClinicaOliverColl","twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/com-es-la-primera-visita-amb-el-denista\/","url":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/com-es-la-primera-visita-amb-el-denista\/","name":"Com \u00e9s la primera visita amb el denista? - Cl\u00ednica dental Oliver Coll","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website"},"datePublished":"2026-07-10T11:16:39+00:00","breadcrumb":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/com-es-la-primera-visita-amb-el-denista\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/com-es-la-primera-visita-amb-el-denista\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/com-es-la-primera-visita-amb-el-denista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadentalolivercoll.com\/ca\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/"},{"@type":"ListItem","position":3,"name":"Com \u00e9s la primera visita amb el denista?"}]},{"@type":"WebSite","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","name":"Cl\u00ednica dental Oliver Coll","description":"Cl\u00ednica dental en Matar\u00f3","publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadentalolivercoll.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization","name":"Cl\u00ednica dental Oliver Coll","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","width":300,"height":300,"caption":"Cl\u00ednica dental Oliver Coll"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClinicaOliverColl","https:\/\/www.instagram.com\/clinicaolivercoll\/"]}]}},"_links":{"self":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/avada_faq\/7610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/avada_faq"}],"about":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/types\/avada_faq"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/comments?post=7610"}],"version-history":[{"count":0,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/avada_faq\/7610\/revisions"}],"wp:attachment":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/media?parent=7610"}],"wp:term":[{"taxonomy":"faq_category","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/faq_category?post=7610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}