{"id":7481,"date":"2026-07-10T10:49:37","date_gmt":"2026-07-10T10:49:37","guid":{"rendered":"https:\/\/olivercoll.staging.dissenyweb.com\/faq-items\/quant-dura-la-intervencio\/"},"modified":"2026-07-10T10:49:37","modified_gmt":"2026-07-10T10:49:37","slug":"quant-dura-la-intervencio","status":"publish","type":"avada_faq","link":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/quant-dura-la-intervencio\/","title":{"rendered":"Quant dura la intervenci\u00f3?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">  Depenent del nombre d&#8217; implants, entre 30 i 60 minuts, enfront de les 1-3 hores de la cirurgia tradicional.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depenent del nombre d&#8217; implants, entre 30 i 60 minuts,  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"faq_category":[404],"class_list":["post-7481","avada_faq","type-avada_faq","status-publish","format-standard","hentry","faq_category-cirurgia-guiada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quant dura la intervenci\u00f3? - Cl\u00ednica dental Oliver Coll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/quant-dura-la-intervencio\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quant dura la intervenci\u00f3? - Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"og:description\" content=\"Depenent del nombre d&#8217; implants, entre 30 i 60 minuts, [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/quant-dura-la-intervencio\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica dental Oliver Coll\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ClinicaOliverColl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/quant-dura-la-intervencio\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/quant-dura-la-intervencio\\\/\",\"name\":\"Quant dura la intervenci\u00f3? - Cl\u00ednica dental Oliver Coll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\"},\"datePublished\":\"2026-07-10T10:49:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/quant-dura-la-intervencio\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/quant-dura-la-intervencio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/quant-dura-la-intervencio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/faq-items\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quant dura la intervenci\u00f3?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"description\":\"Cl\u00ednica dental en Matar\u00f3\",\"publisher\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#organization\",\"name\":\"Cl\u00ednica dental Oliver Coll\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-oliver-coll-blanco-cuadrado.jpg\",\"width\":300,\"height\":300,\"caption\":\"Cl\u00ednica dental Oliver Coll\"},\"image\":{\"@id\":\"https:\\\/\\\/clinicadentalolivercoll.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ClinicaOliverColl\",\"https:\\\/\\\/www.instagram.com\\\/clinicaolivercoll\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quant dura la intervenci\u00f3? - Cl\u00ednica dental Oliver Coll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/quant-dura-la-intervencio\/","og_locale":"ca_ES","og_type":"article","og_title":"Quant dura la intervenci\u00f3? - Cl\u00ednica dental Oliver Coll","og_description":"Depenent del nombre d&#8217; implants, entre 30 i 60 minuts, [...]","og_url":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/quant-dura-la-intervencio\/","og_site_name":"Cl\u00ednica dental Oliver Coll","article_publisher":"https:\/\/www.facebook.com\/ClinicaOliverColl","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/quant-dura-la-intervencio\/","url":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/quant-dura-la-intervencio\/","name":"Quant dura la intervenci\u00f3? - Cl\u00ednica dental Oliver Coll","isPartOf":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website"},"datePublished":"2026-07-10T10:49:37+00:00","breadcrumb":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/quant-dura-la-intervencio\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/quant-dura-la-intervencio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/quant-dura-la-intervencio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clinicadentalolivercoll.com\/ca\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/clinicadentalolivercoll.com\/ca\/faq-items\/"},{"@type":"ListItem","position":3,"name":"Quant dura la intervenci\u00f3?"}]},{"@type":"WebSite","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#website","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","name":"Cl\u00ednica dental Oliver Coll","description":"Cl\u00ednica dental en Matar\u00f3","publisher":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clinicadentalolivercoll.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#organization","name":"Cl\u00ednica dental Oliver Coll","url":"https:\/\/clinicadentalolivercoll.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","contentUrl":"https:\/\/clinicadentalolivercoll.com\/wp-content\/uploads\/2026\/03\/logo-oliver-coll-blanco-cuadrado.jpg","width":300,"height":300,"caption":"Cl\u00ednica dental Oliver Coll"},"image":{"@id":"https:\/\/clinicadentalolivercoll.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ClinicaOliverColl","https:\/\/www.instagram.com\/clinicaolivercoll\/"]}]}},"_links":{"self":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/avada_faq\/7481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/avada_faq"}],"about":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/types\/avada_faq"}],"author":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/comments?post=7481"}],"version-history":[{"count":0,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/avada_faq\/7481\/revisions"}],"wp:attachment":[{"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/media?parent=7481"}],"wp:term":[{"taxonomy":"faq_category","embeddable":true,"href":"https:\/\/clinicadentalolivercoll.com\/ca\/wp-json\/wp\/v2\/faq_category?post=7481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}